{"id":961,"date":"2023-12-29T12:14:11","date_gmt":"2023-12-29T12:14:11","guid":{"rendered":"https:\/\/preprod.idhsuisse.ch\/?p=961"},"modified":"2024-01-12T19:21:31","modified_gmt":"2024-01-12T19:21:31","slug":"prevention-de-la-consommation-de-drogues-un-nouveau-projet-finance","status":"publish","type":"post","link":"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/29\/prevention-de-la-consommation-de-drogues-un-nouveau-projet-finance\/","title":{"rendered":"Pr\u00e9vention de la consommation de drogues: un nouveau projet financ\u00e9"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"961\" class=\"elementor elementor-961\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55f72e5 e-flex e-con-boxed e-con e-parent\" data-id=\"55f72e5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a86753 elementor-widget elementor-widget-text-editor\" data-id=\"1a86753\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span>dim, 2015\/02\/15 &#8211; 19:09<\/span><\/h6>\n<h6><span><br><\/span><\/h6>\n<p>Nous avons le plaisir de vous annoncer qu&rsquo;un nouveau projet a \u00e9t\u00e9 financ\u00e9 pour notre partenaire IDH Bolivia. Il s&rsquo;agit de la mise en place d&rsquo;une section sp\u00e9ciale relative \u00e0 la consommation de drogues dans le cadre de l&rsquo;ExpoSida. Ce projet sera financ\u00e9 par le \u00abfonds drogue\u00bb administr\u00e9 par le Service de la solidarit\u00e9 internationale de la R\u00e9publique et canton de Gen\u00e8ve. Intitul\u00e9 \u00ab<strong>Pr\u00e9vention de la consommation de drogues chez les jeunes \u00e0 Cochabamba<\/strong>\u00bb, ce projet d\u00e9marre en f\u00e9vrier 2015 et est pr\u00e9vu pour une dur\u00e9e initiale de 1 an.<br>\u00bb<span>&nbsp;<\/span><a href=\"https:\/\/www.idhsuisse.ch\/node\/19\">Plus de d\u00e9tails sur la page relative \u00e0 ce projet<\/a><\/p>\n<p><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/logo-coalition.png\" alt=\"Coalition PLUS\" height=\"176\" width=\"175\"><\/p>\n<p><br><\/p>\n<p>Autre bonne nouvelle: IDH Bolivia a \u00e9t\u00e9 accept\u00e9e comme<span>&nbsp;<\/span><strong>membre de plein droit de<span>&nbsp;<\/span><a href=\"http:\/\/www.coalitionplus.org\/\" data-extlink=\"\">Coalition PLUS<span class=\"ext\"><span class=\"element-invisible\">(link is external)<\/span><\/span><\/a><\/strong>, r\u00e9seau international (essentiellement francophone) d&rsquo;associations dont l&rsquo;objectif est de \u00abmettre au centre de ses actions la d\u00e9marche communautaire, en impliquant les personnes infect\u00e9es, affect\u00e9es ou vuln\u00e9rables au VIH\/sida dans tous les processus d\u00e9cisionnels, de r\u00e9alisation et d\u2019\u00e9valuation li\u00e9s aux programmes de lutte contre la pand\u00e9mie\u00bb. En plus de l\u00e9gitimer encore une fois l&rsquo;immense travail d&rsquo;IDH Bolivia dans le domaine de la pr\u00e9vention du VIH\/sida, cela permettra \u00e0 notre partenaire d&rsquo;obtenir quelques fonds propres pour la structure administrative et de coordination des activit\u00e9s.<br>\u00bb<span>&nbsp;<\/span><a href=\"http:\/\/www.coalitionplus.org\/membres\/\" data-extlink=\"\">En savoir plus sur les membres de Coalition PLUS<\/a><\/p><p><br><\/p>\n<p>Derni\u00e8re info:<span>&nbsp;<\/span><strong>Anne sera de passage<\/strong><span>&nbsp;<\/span>\u00e0 Paris pour une r\u00e9union fin avril, et viendra \u00e0 Gen\u00e8ve d\u00e9but mai. Nous pr\u00e9voyons donc de fixer notre prochaine assembl\u00e9e g\u00e9n\u00e9rale pendant son s\u00e9jour. Nous vous communiquerons la date exacte ult\u00e9rieurement.<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>dim, 2015\/02\/15 &#8211; 19:09 Nous avons le plaisir de vous annoncer qu&rsquo;un nouveau projet a \u00e9t\u00e9 financ\u00e9 pour notre partenaire IDH Bolivia. Il s&rsquo;agit de la mise en place d&rsquo;une section sp\u00e9ciale relative \u00e0 la consommation de drogues dans le cadre de l&rsquo;ExpoSida. Ce projet sera financ\u00e9 par le \u00abfonds [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":659,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[7],"tags":[40,19,33,36,18,32,16],"class_list":["post-961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter","tag-assemble","tag-drogue","tag-financement","tag-partenariat","tag-prevention","tag-projets","tag-sante"],"_links":{"self":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/comments?post=961"}],"version-history":[{"count":10,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/961\/revisions"}],"predecessor-version":[{"id":971,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/961\/revisions\/971"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/media\/659"}],"wp:attachment":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/media?parent=961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/categories?post=961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/tags?post=961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}