{"id":501,"date":"2023-12-28T13:28:26","date_gmt":"2023-12-28T13:28:26","guid":{"rendered":"https:\/\/preprod.idhsuisse.ch\/?p=501"},"modified":"2024-01-12T19:29:36","modified_gmt":"2024-01-12T19:29:36","slug":"de-lespace-prive-a-la-societe-civile-une-sexualite-sans-derapage","status":"publish","type":"post","link":"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/de-lespace-prive-a-la-societe-civile-une-sexualite-sans-derapage\/","title":{"rendered":"De l\u2019espace priv\u00e9 \u00e0 la soci\u00e9t\u00e9 civile: une sexualit\u00e9 sans d\u00e9rapage"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"501\" class=\"elementor elementor-501\">\n\t\t\t\t<div class=\"elementor-element elementor-element-172e111 e-con-full e-flex e-con e-parent\" data-id=\"172e111\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f373ba1 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"f373ba1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"field field-name-body field-type-text-with-summary field-label-hidden\"><div class=\"field-items\"><div class=\"field-item even\" property=\"content:encoded\"><p>Le projet de notre partenaire, qui a d\u00e9but\u00e9 en 2013, r\u00e9sulte d\u2019une part d\u2019une prise de conscience en Bolivie du nombre et de la gravit\u00e9 des violences sexuelles en particulier envers les enfants, et d\u2019autre part de violences qui peuvent s\u2019instaurer au sein d\u2019un couple nouvellement form\u00e9; il part du constat qu\u2019une violence exerc\u00e9e au sein d\u2019un espace priv\u00e9 a \u00e9galement une incidence sur la soci\u00e9t\u00e9 en g\u00e9n\u00e9ral.<\/p><p>Le projet, qui b\u00e9n\u00e9ficie d&rsquo;un financement de la<span>\u00a0<\/span><a href=\"http:\/\/www.fgc.ch\/\" target=\"_blank\" data-extlink=\"\" rel=\"noopener\">FGC<span class=\"ext\"><span class=\"element-invisible\">(link is external)<\/span><\/span><\/a>, se d\u00e9veloppe dans les \u00e9tablissements scolaires et les familles de Quillacollo, vise les enfants de 12-14 ans afin de les renforcer face aux risques d\u2019abus sexuels, ainsi que les jeunes de 15-18 ans afin de favoriser des premi\u00e8res relations amoureuses sans violence.<\/p><p>Avant tout \u00e9ducatif, pr\u00e9ventif et orient\u00e9 sur les jeunes, leurs familles et les \u00e9tablissements scolaires, ce projet b\u00e9n\u00e9ficie de toute l\u2019exp\u00e9rience et la r\u00e9putation qu\u2019IDH Bolivia a tiss\u00e9es par son programme Sid\u2019Accion. \u00c0 nouveau, il se d\u00e9veloppe en partenariat avec les autorit\u00e9s \u00e9ducatives et comporte une forte dimension d\u2019incidence politique, c.-\u00e0.-d. de responsabilisation des pouvoirs publics.<\/p><\/div><\/div><\/div><div class=\"field field-name-field-file field-type-file field-label-above\"><div class=\"field-label\">File(s):\u00a0<\/div><div class=\"field-items\"><div class=\"field-item even\"><span class=\"file\"><img decoding=\"async\" class=\"file-icon\" alt=\"PDF icon\" title=\"application\/pdf\" src=\"https:\/\/www.idhsuisse.ch\/modules\/file\/icons\/application-pdf.png\" \/><span>\u00a0<\/span><a href=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/pdf\/presentation_idhbolivia_avril2015.pdf\" type=\"application\/pdf; length=5198283\" title=\"presentation_idhbolivia_avril2015.pdf\">Pr\u00e9sentation du projet, avril 2015<\/a><\/span><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Le projet de notre partenaire, qui a d\u00e9but\u00e9 en 2013, r\u00e9sulte d\u2019une part d\u2019une prise de conscience en Bolivie du nombre et de la gravit\u00e9 des violences sexuelles en particulier envers les enfants, et d\u2019autre part de violences qui peuvent s\u2019instaurer au sein d\u2019un couple nouvellement form\u00e9; il part du [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":98,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[23],"tags":[15,21,20,17,14],"class_list":["post-501","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-termine","tag-education","tag-famille","tag-jeunes","tag-sexe","tag-violence"],"_links":{"self":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/501","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/comments?post=501"}],"version-history":[{"count":16,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/501\/revisions"}],"predecessor-version":[{"id":1013,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/501\/revisions\/1013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/media\/98"}],"wp:attachment":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/media?parent=501"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/categories?post=501"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/tags?post=501"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}