{"id":1134,"date":"2023-12-29T13:48:29","date_gmt":"2023-12-29T13:48:29","guid":{"rendered":"https:\/\/preprod.idhsuisse.ch\/?p=1134"},"modified":"2024-01-12T19:15:01","modified_gmt":"2024-01-12T19:15:01","slug":"semaines-tinkunapaq-a-cochabamba","status":"publish","type":"post","link":"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/29\/semaines-tinkunapaq-a-cochabamba\/","title":{"rendered":"Semaines TinkuNapaq \u00e0 Cochabamba"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1134\" class=\"elementor elementor-1134\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d6a7ff e-flex e-con-boxed e-con e-parent\" data-id=\"4d6a7ff\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0d9af34 elementor-widget elementor-widget-text-editor\" data-id=\"0d9af34\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h6><span>mer, 2018\/10\/03 &#8211; 22:05<\/span><\/h6><h6><span>\u00a0<\/span><\/h6><p>Entre le 27 ao\u00fbt et le 6 septembre,<span>\u00a0<\/span><strong>l\u2019Instituto para el Desarrollo Humano (IDH)<\/strong><span>\u00a0<\/span>a organis\u00e9 plusieurs \u00e9v\u00e9nements sous le titre de Tinku Napaq, expression quechua que signifie<span>\u00a0<\/span><strong>se battre pour des id\u00e9es.<\/strong><\/p><p>La pr\u00e9sence de Coalition Plus a \u00e9t\u00e9 soulign\u00e9e, notamment lors de l\u2019inauguration de l\u2019exposition<span>\u00a0<\/span><strong>\u00abPreparemos un mundo sin sida\u00bb<\/strong><span>\u00a0<\/span>qui pr\u00e9sente les nouvelles strat\u00e9gies de la pr\u00e9vention combin\u00e9e et l\u2019importance de la non discrimination pour atteindre les objectifs 90-90-90 d\u2019une fa\u00e7on simple, \u00e0 laquelle ont particip\u00e9 les consuls de France, Suisse et la Responsable de l\u2019Agence fran\u00e7aise de D\u00e9veloppement pour la Bolivie. Un espace d\u2019information sur les 10 ann\u00e9es de Coalition Plus a \u00e9t\u00e9 am\u00e9nag\u00e9, illustrant quelques activit\u00e9s de ses membres, notamment d\u2019IDH Bolivie.<\/p><table><tbody><tr><td><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/1.png\" alt=\"Inauguration de l'exposition \u00abPreparemos un mundo sin sida\u00bb\" title=\"Inauguration de l'exposition \u00abPreparemos un mundo sin sida\u00bb\" height=\"300\" \/><\/td><td><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/2.png\" alt=\"Inauguration de l'exposition \u00abPreparemos un mundo sin sida\u00bb\" title=\"Inauguration de l'exposition \u00abPreparemos un mundo sin sida\u00bb\" height=\"300\" \/><\/td><\/tr><\/tbody><\/table><pre>Inauguration, photo de gauche: Cordula Th\u00f6ny, Consul de Suisse \u00e0 Cochabamba; Neige Pruvost, direcrice de l\u2019Alliance fran\u00e7aise de Cochabamba; Emanuel Lung, Consul de France \u00e0 Cochabamba; Carine Megueulle, Responsable de l\u2019Agence Fran\u00e7aise de D\u00e9veloppement pour Bolivie; Edgar Valdez, directeur de l\u2019Instituto para el Desarrollo Humano; Vincent Pelletier, directeur de Coalition Plus; Anne Saudan, Instituto para el Desarrollo Humano; Dr. Joaquin Salcedo, Pr\u00e9sident de l\u2019Instituto para el Desarrollo Humano<br \/>Photo de droite: Daniela Rojas et Vincent Pelletier de Coalition Plus (France)<\/pre><p><strong>Daniela Rojas, Responsable du Programme Recherche de Coalition Plus<\/strong>, a pu \u00e9changer avec l\u2019\u00e9quipe de IDH au sujet des recherches communautaires lors d\u2019une r\u00e9union interne dans le but d\u2019am\u00e9liorer le niveau et la participation des populations vuln\u00e9rables tout au long du parcours des enqu\u00eates.<\/p><p>Le<span>\u00a0<\/span><strong>premier Conversatorio<\/strong><span>\u00a0<\/span>s\u2019est d\u00e9roul\u00e9 avec la pr\u00e9sence de 24 personnes de 13 organisations de la soci\u00e9t\u00e9 civile (LGBT, personnes vivant avec le VIH, association des jeunes avec le VIH, travailleurs du sexe, conseil juv\u00e9nile d\u2019IDH, volontaires, etc.), qui ont \u00e9chang\u00e9 sur la situation en rapport aux objectifs 90-90-90. Dans les conclusions, il s\u2019av\u00e8re que<span>\u00a0<\/span><a href=\"http:\/\/www.opinion.com.bo\/opinion\/articulos\/noticias.php?a=2018&amp;md=0906&amp;id=266067\" data-extlink=\"\">la Bolivie n\u2019utilise pas tous les moyens \u00e0 sa disposition pour lutter contre l\u2019\u00e9pid\u00e9mie<span class=\"ext\"><span class=\"element-invisible\">(link is external)<\/span><\/span><\/a>, qu\u2019il est n\u00e9cessaire de travailler sur un agenda global et non fractionn\u00e9 par population vuln\u00e9rable et qu\u2019il faut former de nouveaux liderships dans chaque population. L\u2019IDH a offert son appui pour le renforcement des capacit\u00e9s de ces organisations.<\/p><p>D\u2019autre part, le<span>\u00a0<\/span><strong>s\u00e9minaire international<\/strong><span>\u00a0<\/span>a permis pendant 2 jours de parler de la pr\u00e9vention combin\u00e9e, de l\u2019approche communautaire et du cycle de vie des personnes avec le VIH<span>\u00a0<\/span><strong>\u00abNacer, vivir y envejecer con el VIH\u00bb<\/strong>. La pr\u00e9sence de<span>\u00a0<\/span><strong>5 exposants de France, Argentine et P\u00e9rou<\/strong>, la plupart activistes, a offert une nouvelle facette du sujet pour les 425 personnes pr\u00e9sentes, essentiellement des services de sant\u00e9, \u00e9tudiants, mais aussi liders des communaut\u00e9s vuln\u00e9rables. Une m\u00e9moire du S\u00e9minaire a \u00e9t\u00e9 diffus\u00e9e, soulignant les points forts de ces deux journ\u00e9es d\u2019actualisation.<\/p><table><tbody><tr><td><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/6.png\" alt=\"S\u00e9minaire international \u00abNacer, vivir y envejecer con el VIH\u00bb\" title=\"S\u00e9minaire international \u00abNacer, vivir y envejecer con el VIH\u00bb\" height=\"300\" \/><\/td><td><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/7.png\" alt=\"S\u00e9minaire international \u00abNacer, vivir y envejecer con el VIH\u00bb\" title=\"S\u00e9minaire international \u00abNacer, vivir y envejecer con el VIH\u00bb\" height=\"300\" \/><\/td><\/tr><\/tbody><\/table><p><a href=\"http:\/\/www.corresponsalesclave.org\/2018\/09\/seminario-bolivia-idh.html\" data-extlink=\"\">Le s\u00e9minaire a \u00e9t\u00e9 relay\u00e9 par les \u00abcorrespondants cl\u00e9s\u00bb<span class=\"ext\"><span class=\"element-invisible\">(link is external)<\/span><\/span><\/a>, r\u00e9seau latino am\u00e9ricain de journalistes sur le VIH.<\/p><p>De fa\u00e7on parall\u00e8le, l\u2019\u00e9quipe a organis\u00e9 une courte session de th\u00e9\u00e2tre sur la pr\u00e9vention de la consommation des drogues et la violence dans les premi\u00e8res relations de couple, \u00abNo te metas en mi vida\u00bb pr\u00e9sent\u00e9e par le groupe \u00abAl Toque\u00bb dans certains coll\u00e8ges publics de Cochabamba, de Quillacollo et de Colcapirhua. Plus de 7000 \u00e9l\u00e8ves ont ainsi pu participer \u00e0 ce moment \u00e0 la fois humoristique et r\u00e9flexif, qui donnait lieu \u00e0 un court d\u00e9bat. Les commentaires des \u00e9l\u00e8ves et des enseignants-es ont d\u00e9montr\u00e9 que cette forme de pr\u00e9vention est appr\u00e9ci\u00e9e et permet de renforcer le travail en classe.<\/p><table><tbody><tr><td><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/11.png\" alt=\"Session de th\u00e9\u00e2tre \u00abNo te metas en mi vida\u00bb\" title=\"Session de th\u00e9\u00e2tre \u00abNo te metas en mi vida\u00bb\" height=\"300\" \/><\/td><td><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/9.png\" alt=\"Session de th\u00e9\u00e2tre \u00abNo te metas en mi vida\u00bb\" title=\"Session de th\u00e9\u00e2tre \u00abNo te metas en mi vida\u00bb\" height=\"300\" \/><\/td><td><img decoding=\"async\" src=\"https:\/\/www.idhsuisse.ch\/sites\/idhsuisse.ch\/files\/8.png\" alt=\"Session de th\u00e9\u00e2tre \u00abNo te metas en mi vida\u00bb\" title=\"Session de th\u00e9\u00e2tre \u00abNo te metas en mi vida\u00bb\" height=\"300\" \/><\/td><\/tr><\/tbody><\/table><p>Ces diff\u00e9rents \u00e9v\u00e9nements ont pu \u00eatre organis\u00e9s gr\u00e2ce aux financements de la F\u00e9d\u00e9ration Genevoise de Coop\u00e9ration, la Centrale Sanitaire Suisse (FEDEVACO), Le Service de Solidarit\u00e9 Internationale du canton de Gen\u00e8ve (fonds drogues), Pain pour le Monde-Allemagne, Alliance Internationale et Coalition Plus pour les frais li\u00e9s aux conf\u00e9renciers internationaux.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>mer, 2018\/10\/03 &#8211; 22:05 \u00a0 Entre le 27 ao\u00fbt et le 6 septembre,\u00a0l\u2019Instituto para el Desarrollo Humano (IDH)\u00a0a organis\u00e9 plusieurs \u00e9v\u00e9nements sous le titre de Tinku Napaq, expression quechua que signifie\u00a0se battre pour des id\u00e9es. La pr\u00e9sence de Coalition Plus a \u00e9t\u00e9 soulign\u00e9e, notamment lors de l\u2019inauguration de l\u2019exposition\u00a0\u00abPreparemos un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1139,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_eb_attr":"","footnotes":""},"categories":[7],"tags":[19,35,16,17,14,43],"class_list":["post-1134","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-newsletter","tag-drogue","tag-evenements","tag-sante","tag-sexe","tag-violence","tag-visite"],"_links":{"self":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/1134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1134"}],"version-history":[{"count":7,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/1134\/revisions"}],"predecessor-version":[{"id":1148,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/posts\/1134\/revisions\/1148"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/media\/1139"}],"wp:attachment":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1134"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/categories?post=1134"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/tags?post=1134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}