{"id":1249,"date":"2023-12-29T15:11:12","date_gmt":"2023-12-29T15:11:12","guid":{"rendered":"https:\/\/preprod.idhsuisse.ch\/?page_id=1249"},"modified":"2024-09-14T18:09:23","modified_gmt":"2024-09-14T18:09:23","slug":"home","status":"publish","type":"page","link":"https:\/\/preprod.idhsuisse.ch\/","title":{"rendered":"Home"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1249\" class=\"elementor elementor-1249\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b7203ac e-flex e-con-boxed e-con e-parent\" data-id=\"b7203ac\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4641b61 elementor-widget elementor-widget-image\" data-id=\"4641b61\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"300\" height=\"183\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/cropped-Nouveau-logo-IDH-Suisse-300x183.png\" class=\"attachment-medium size-medium wp-image-475\" alt=\"\" srcset=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/cropped-Nouveau-logo-IDH-Suisse-300x183.png 300w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/cropped-Nouveau-logo-IDH-Suisse-1024x626.png 1024w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/cropped-Nouveau-logo-IDH-Suisse-768x469.png 768w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/cropped-Nouveau-logo-IDH-Suisse.png 1522w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8774695 elementor-widget__width-initial elementor-widget elementor-widget-heading\" data-id=\"8774695\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sant\u00e9, Droits Humains et Environnement en Bolivie<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d20741 e-con-full e-flex e-con e-child\" data-id=\"3d20741\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ebe0fff elementor-widget elementor-widget-text-editor\" data-id=\"ebe0fff\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"has-text-align-center\"><strong>Bienvenue \u00e0 l\u2019Institut pour le D\u00e9veloppement Humain, IDH Suisse\u00a0<\/strong><\/h2>\n<div>\n<br> \n<p class=\"has-text-align-center\" style=\"font-size: 20px; text-align: justify;\"><span style=\"font-size: inherit; text-align: var(--text-align);\">IDH Suisse est une organisation \u00e0 but non lucratif, cr\u00e9\u00e9e en 2017. Notre principale mission est de soutenir les activit\u00e9s de l\u2019<\/span><a href=\"https:\/\/idhbolivia.org\/\" data-type=\"link\" data-id=\"https:\/\/idhbolivia.org\/\" style=\"font-size: inherit; text-align: var(--text-align);\">IpDH Bolivia<\/a><span style=\"font-size: inherit; text-align: var(--text-align);\">, l\u2019<\/span><em style=\"font-size: inherit; text-align: var(--text-align);\">Instituto para el Desarrollo Humano<\/em><span style=\"font-size: inherit; text-align: var(--text-align);\">\u00a0<\/span><span style=\"font-size: inherit; text-align: var(--text-align);\">dans son engagement envers la population locale et la d\u00e9fense des droits humains.<\/span><\/p>\n<p style=\"font-size: 20px; text-align: justify;\">IpDH Bolivia a \u00e9t\u00e9 cr\u00e9\u00e9e en 1997 dans le but de lutter contre le VIH. Au cours des vingt-six derni\u00e8res ann\u00e9es, cette ONG est devenue un\u00a0<a href=\"https:\/\/www.opinion.com.bo\/articulo\/revista-asi\/corazon-detras-idh-pareja-que-consolido-proyecto-que-combate-vih-bolivia\/20221202212258889543.html\" data-type=\"link\" data-id=\"https:\/\/www.opinion.com.bo\/articulo\/revista-asi\/corazon-detras-idh-pareja-que-consolido-proyecto-que-combate-vih-bolivia\/20221202212258889543.html\">acteur majeur\u00a0<\/a>du soutien \u00e0 la population locale et de la d\u00e9fense des droits humains.<\/p>\n\n<\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3070305 e-con-full e-flex e-con e-child\" data-id=\"3070305\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d205310 elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"d205310\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=8lDRiL-0MyM&amp;ab_channel=InstitutoparaelDesarrolloHumano-Bolivia&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-549a680 e-flex e-con-boxed e-con e-parent\" data-id=\"549a680\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0240dd5 e-con-full e-flex e-con e-child\" data-id=\"0240dd5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4b10e85 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"4b10e85\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong>IDH Suisse soutient IpDH Bolivia<\/strong> notamment \u00e0 travers la recherche de fonds.<\/p><p>Depuis ses d\u00e9buts, IDH Suisse est un membre actif de la <a href=\"https:\/\/www.fgc.ch\/\">F\u00e9d\u00e9ration Genevoise de Coop\u00e9ration (FGC<\/a><span style=\"font-size: inherit; text-align: var(--text-align);\">), qui oeuvre au financement de projets de d\u00e9veloppement align\u00e9s sur les Objectifs de D\u00e9veloppement Durable d\u00e9finis par les Nations Unies. <\/span>\u00c0 travers des liens \u00e9troits avec IpDH Bolivia, IDH Suisse assure un suivi constant des projets r\u00e9alis\u00e9s sur le terrain afin de fournir les ressources n\u00e9cessaires.<\/p><p>Les fonds r\u00e9colt\u00e9s sous formes de donations priv\u00e9s, cotisations et relations publiques sont vers\u00e9s en totalit\u00e9 \u00e0 IpDH Bolivia.<\/p><p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1429e28 e-con-full e-flex e-con e-child\" data-id=\"1429e28\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2a4ba15 elementor-widget elementor-widget-image\" data-id=\"2a4ba15\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/3-liders-presentation-du-projet-scaled.jpg\" title=\"Pr\u00e9sentation du projet Scaled\" alt=\"Pr\u00e9sentation du projet Scaled\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20ded9e bdt-backdrop-filter-yes e-flex e-con-boxed e-con e-parent\" data-id=\"20ded9e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;xpro_backdrop_filter&quot;:&quot;yes&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1574c48 elementor-widget elementor-widget-heading\" data-id=\"1574c48\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\"><br> Projets en cours<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f2a4d5b e-con-full e-flex e-con e-child\" data-id=\"f2a4d5b\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2add3b0 elementor-widget elementor-widget-htmega-postcarousel-addons\" data-id=\"2add3b0\" data-element_type=\"widget\" data-settings=\"{&quot;carousel_post_type&quot;:&quot;post&quot;}\" data-widget_type=\"htmega-postcarousel-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t            <div class=\"post-carousel-wrapper htmega-postcarousel-layout-2 htmega-verticle-center-arrow sid2add3b0\">\n                <div dir=\"ltr\" class=\"htmega-carousel-activation\" data-settings=\"{&quot;sectionid&quot;:&quot;sid2add3b0&quot;,&quot;arrows&quot;:true,&quot;arrow_prev_txt&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-angle-left\\&quot; viewBox=\\&quot;0 0 256 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M31.7 239l136-136c9.4-9.4 24.6-9.4 33.9 0l22.6 22.6c9.4 9.4 9.4 24.6 0 33.9L127.9 256l96.4 96.4c9.4 9.4 9.4 24.6 0 33.9L201.7 409c-9.4 9.4-24.6 9.4-33.9 0l-136-136c-9.5-9.4-9.5-24.6-.1-34z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;arrow_next_txt&quot;:&quot;&lt;svg class=\\&quot;e-font-icon-svg e-fas-angle-right\\&quot; viewBox=\\&quot;0 0 256 512\\&quot; xmlns=\\&quot;http:\\\/\\\/www.w3.org\\\/2000\\\/svg\\&quot;&gt;&lt;path d=\\&quot;M224.3 273l-136 136c-9.4 9.4-24.6 9.4-33.9 0l-22.6-22.6c-9.4-9.4-9.4-24.6 0-33.9l96.4-96.4-96.4-96.4c-9.4-9.4-9.4-24.6 0-33.9L54.3 103c9.4-9.4 24.6-9.4 33.9 0l136 136c9.5 9.4 9.5 24.6.1 34z\\&quot;&gt;&lt;\\\/path&gt;&lt;\\\/svg&gt;&quot;,&quot;dots&quot;:true,&quot;autoplay&quot;:true,&quot;autoplay_speed&quot;:6000,&quot;animation_speed&quot;:300,&quot;slloop&quot;:true,&quot;pause_on_hover&quot;:true,&quot;center_mode&quot;:false,&quot;center_padding&quot;:0,&quot;equal_height_column&quot;:true,&quot;equal_height_column_class&quot;:&quot;.post-inner&quot;,&quot;display_columns&quot;:3,&quot;scroll_columns&quot;:1,&quot;tablet_width&quot;:750,&quot;tablet_display_columns&quot;:1,&quot;tablet_scroll_columns&quot;:1,&quot;mobile_width&quot;:480,&quot;mobile_display_columns&quot;:1,&quot;mobile_scroll_columns&quot;:1}\" style=\"display:none;\">\n\n                    \n                                                    <div class=\"htmega-single-post-slide htmega-postslider-layout-2\" >\n                                <div class=\"thumb\">\n                                    <a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/projet-golondrina-prevention-dirigee-aux-migrants-en-bolivie\/\"><img decoding=\"async\" width=\"444\" height=\"295\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/session_avec_parents_d_eleves-scaled.jpg\" class=\"attachment-htmega_size_585x295 size-htmega_size_585x295 wp-post-image\" alt=\"\" srcset=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/session_avec_parents_d_eleves-scaled.jpg 2560w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/session_avec_parents_d_eleves-300x199.jpg 300w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/session_avec_parents_d_eleves-1024x680.jpg 1024w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/session_avec_parents_d_eleves-768x510.jpg 768w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/session_avec_parents_d_eleves-1536x1021.jpg 1536w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/session_avec_parents_d_eleves-2048x1361.jpg 2048w\" sizes=\"(max-width: 444px) 100vw, 444px\" \/><\/a>\n                                <\/div>\n                                            <div class=\"content htmega-solid\">\n                <div class=\"post-inner\">\n                    \n                    \n                                                <h2><a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/projet-golondrina-prevention-dirigee-aux-migrants-en-bolivie\/\">Projet \u201cGolondrina\u201d, pr\u00e9vention dirig\u00e9e aux migrants en Bolivie<\/a><\/h2>\n                        \n                    \n                    <p>Observatoire et acc\u00e8s aux services de sant\u00e9 pour les populations migrantes vuln\u00e9rables au VIH.Soutenu par Agence Fran\u00e7aise deD\u00e9veloppement (AFD), Coalition<\/p>\n                    \n                                            <div class=\"post-btn\">\n                            <a class=\"readmore-btn\" href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/projet-golondrina-prevention-dirigee-aux-migrants-en-bolivie\/\">En Savoir Plus<\/a>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n                                    <\/div>\n\n                        \n                        \n                                                    <div class=\"htmega-single-post-slide htmega-postslider-layout-2\" >\n                                <div class=\"thumb\">\n                                    <a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/renforcement-des-services-amicaux-et-perennes-de-soins-integraux-pour-les-personnes-touchee-par-le-vih-et-populations-vulnerables\/\"><img decoding=\"async\" width=\"400\" height=\"295\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/dh002.jpg\" class=\"attachment-htmega_size_585x295 size-htmega_size_585x295 wp-post-image\" alt=\"\" srcset=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/dh002.jpg 434w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/dh002-300x221.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/a>\n                                <\/div>\n                                            <div class=\"content htmega-solid\">\n                <div class=\"post-inner\">\n                    \n                    \n                                                <h2><a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/renforcement-des-services-amicaux-et-perennes-de-soins-integraux-pour-les-personnes-touchee-par-le-vih-et-populations-vulnerables\/\">Renforcement des services amicaux et p\u00e9rennes de soins int\u00e9graux pour les personnes touch\u00e9e par le VIH et populations vuln\u00e9rables<\/a><\/h2>\n                        \n                    \n                    <p>Suivi des personnes avec le VIH et populations cl\u00e9 (Hommes ayant des relations sexuelles avec d\u2019autres hommes, Trans, Travailleurs du<\/p>\n                    \n                                            <div class=\"post-btn\">\n                            <a class=\"readmore-btn\" href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/renforcement-des-services-amicaux-et-perennes-de-soins-integraux-pour-les-personnes-touchee-par-le-vih-et-populations-vulnerables\/\">En Savoir Plus<\/a>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n                                    <\/div>\n\n                        \n                        \n                                                    <div class=\"htmega-single-post-slide htmega-postslider-layout-2\" >\n                                <div class=\"thumb\">\n                                    <a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/renforcement-de-la-prise-en-charge-integrale-des-populations-vulnerables-au-vih-a-cochabamba\/\"><img loading=\"lazy\" decoding=\"async\" width=\"393\" height=\"295\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/Exposition-sur-les-nouveaux-concepts-du-VIH-scaled.jpg\" class=\"attachment-htmega_size_585x295 size-htmega_size_585x295 wp-post-image\" alt=\"\" srcset=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/Exposition-sur-les-nouveaux-concepts-du-VIH-scaled.jpg 2560w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/Exposition-sur-les-nouveaux-concepts-du-VIH-300x225.jpg 300w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/Exposition-sur-les-nouveaux-concepts-du-VIH-1024x768.jpg 1024w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/Exposition-sur-les-nouveaux-concepts-du-VIH-768x576.jpg 768w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/Exposition-sur-les-nouveaux-concepts-du-VIH-1536x1152.jpg 1536w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/Exposition-sur-les-nouveaux-concepts-du-VIH-2048x1536.jpg 2048w\" sizes=\"(max-width: 393px) 100vw, 393px\" \/><\/a>\n                                <\/div>\n                                            <div class=\"content htmega-solid\">\n                <div class=\"post-inner\">\n                    \n                    \n                                                <h2><a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/renforcement-de-la-prise-en-charge-integrale-des-populations-vulnerables-au-vih-a-cochabamba\/\">Renforcement de la prise en charge int\u00e9grale des populations vuln\u00e9rables au VIH \u00e0 Cochabamba<\/a><\/h2>\n                        \n                    \n                    <p>Suivi des personnes avec le VIH et populations cl\u00e9 (Hommes ayant des relations sexuelles avec d\u2019autres hommes, Trans, Travailleurs du<\/p>\n                    \n                                            <div class=\"post-btn\">\n                            <a class=\"readmore-btn\" href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/renforcement-de-la-prise-en-charge-integrale-des-populations-vulnerables-au-vih-a-cochabamba\/\">En Savoir Plus<\/a>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n                                    <\/div>\n\n                        \n                        \n                                                    <div class=\"htmega-single-post-slide htmega-postslider-layout-2\" >\n                                <div class=\"thumb\">\n                                    <a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/prevention-de-la-traite-et-le-traffic-dadolescents-es\/\"><img loading=\"lazy\" decoding=\"async\" width=\"444\" height=\"295\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/formation_de_l_equipe_sur_la_violence_sexuelle_Mario_Zarate_Mejico.jpg\" class=\"attachment-htmega_size_585x295 size-htmega_size_585x295 wp-post-image\" alt=\"\" srcset=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/formation_de_l_equipe_sur_la_violence_sexuelle_Mario_Zarate_Mejico.jpg 1404w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/formation_de_l_equipe_sur_la_violence_sexuelle_Mario_Zarate_Mejico-300x199.jpg 300w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/formation_de_l_equipe_sur_la_violence_sexuelle_Mario_Zarate_Mejico-1024x680.jpg 1024w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/formation_de_l_equipe_sur_la_violence_sexuelle_Mario_Zarate_Mejico-768x510.jpg 768w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/formation_de_l_equipe_sur_la_violence_sexuelle_Mario_Zarate_Mejico-360x240.jpg 360w\" sizes=\"(max-width: 444px) 100vw, 444px\" \/><\/a>\n                                <\/div>\n                                            <div class=\"content htmega-solid\">\n                <div class=\"post-inner\">\n                    \n                    \n                                                <h2><a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/prevention-de-la-traite-et-le-traffic-dadolescents-es\/\">Pr\u00e9vention de la traite et le traffic d\u2019adolescents-es<\/a><\/h2>\n                        \n                    \n                    <p>Pr\u00e9vention dans les coll\u00e8ges de la zone rurale de Cochabamba. Formation des enseignants-es sur les outils p\u00e9dagogiques simples afin d\u2019aborder<\/p>\n                    \n                                            <div class=\"post-btn\">\n                            <a class=\"readmore-btn\" href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/prevention-de-la-traite-et-le-traffic-dadolescents-es\/\">En Savoir Plus<\/a>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n                                    <\/div>\n\n                        \n                        \n                                                    <div class=\"htmega-single-post-slide htmega-postslider-layout-2\" >\n                                <div class=\"thumb\">\n                                    <a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/damour-et-de-sexe-renforcement-de-la-sante-sexuelle-et-affective-des-adolescents-es-de-cochabamba-bolivie\/\"><img loading=\"lazy\" decoding=\"async\" width=\"407\" height=\"295\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/ASM.jpg\" class=\"attachment-htmega_size_585x295 size-htmega_size_585x295 wp-post-image\" alt=\"\" srcset=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/ASM.jpg 820w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/ASM-300x218.jpg 300w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/11\/ASM-768x557.jpg 768w\" sizes=\"(max-width: 407px) 100vw, 407px\" \/><\/a>\n                                <\/div>\n                                            <div class=\"content htmega-solid\">\n                <div class=\"post-inner\">\n                    \n                    \n                                                <h2><a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/damour-et-de-sexe-renforcement-de-la-sante-sexuelle-et-affective-des-adolescents-es-de-cochabamba-bolivie\/\">\u201cD\u2019Amour et de sexe\u201d, Renforcement de la sant\u00e9 sexuelle et affective des adolescents-es de Cochabamba, Bolivie<\/a><\/h2>\n                        \n                    \n                    <p>Pr\u00e9vention aupr\u00e8s des jeunes et adolescents-es \u00e0 travers les nouvelles technologies. Plateforme sur la sexualit\u00e9, utilisant la page Web, la<\/p>\n                    \n                                            <div class=\"post-btn\">\n                            <a class=\"readmore-btn\" href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2023\/12\/28\/damour-et-de-sexe-renforcement-de-la-sante-sexuelle-et-affective-des-adolescents-es-de-cochabamba-bolivie\/\">En Savoir Plus<\/a>\n                        <\/div>\n                    \n                <\/div>\n            <\/div>\n                                    <\/div>\n\n                        \n                        \n                <\/div>\n            <\/div>\n            \n            \n\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e829ba8 e-flex e-con-boxed e-con e-parent\" data-id=\"e829ba8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-7637a9a e-con-full e-flex e-con e-child\" data-id=\"7637a9a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-03d4bf2 elementor-widget elementor-widget-heading\" data-id=\"03d4bf2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br><br><br> <br>Nos Publications les plus r\u00e9centes: <\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6f56c94 e-con-full e-flex e-con e-child\" data-id=\"6f56c94\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d7f2dd9 xpro-widget-bg-overlay elementor-widget elementor-widget-htmega-singlepost-addons\" data-id=\"d7f2dd9\" data-element_type=\"widget\" data-widget_type=\"htmega-singlepost-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t                            <div class=\"htmega-single-post htmega-single-post-style-3 secidd7f2dd9\">\n                    <div class=\"thumb\">\n                        <a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2024\/09\/14\/elementor-1654\/\">\n                            <img loading=\"lazy\" decoding=\"async\" width=\"1411\" height=\"1159\" src=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/10.Visita-a-la-Exposicion-OJO-con-la-violencia.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" srcset=\"https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/10.Visita-a-la-Exposicion-OJO-con-la-violencia.png 1411w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/10.Visita-a-la-Exposicion-OJO-con-la-violencia-300x246.png 300w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/10.Visita-a-la-Exposicion-OJO-con-la-violencia-1024x841.png 1024w, https:\/\/preprod.idhsuisse.ch\/wp-content\/uploads\/2023\/12\/10.Visita-a-la-Exposicion-OJO-con-la-violencia-768x631.png 768w\" sizes=\"(max-width: 1411px) 100vw, 1411px\" \/>                        <\/a>\n                    <\/div>\n                    <div class=\"content\">\n                                                        <h2><a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/2024\/09\/14\/elementor-1654\/\">Recrutement de nouveaux membres pour le comit\u00e9 d&rsquo;IDH Suisse<\/a><\/h2>\n                                                                                <ul class=\"meta\">\n                                                                    <li><i class=\"fa fa-clock-o\"><\/i>14 septembre 2024<\/li>\n                                                            <\/ul>\n                                            <\/div>\n                <\/div>\n\n            \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e861a8a e-flex e-con-boxed e-con e-parent\" data-id=\"e861a8a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a522ffd elementor-widget elementor-widget-heading\" data-id=\"a522ffd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br><br><br>Soutenez les activit\u00e9s d'IDH Suisse et IpDH Bolivia<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2d567de e-con-full e-flex e-con e-child\" data-id=\"2d567de\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-81b1e2e elementor-widget elementor-widget-heading\" data-id=\"81b1e2e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><br>Faites un <span style=\"background: white;color:purple\"> Don<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-debcf81 e-con-full e-flex e-con e-child\" data-id=\"debcf81\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a296849 elementor-widget elementor-widget-htmega-button-addons\" data-id=\"a296849\" data-element_type=\"widget\" data-widget_type=\"htmega-button-addons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"htmega-button htmega-btn-style-1 htmega-btn-shadow-0\"><a href=\"https:\/\/preprod.idhsuisse.ch\/index.php\/faire-un-don\/\" class=\"htb-btn htmega-btn-size-md htmega-btn-effect-1\">Donation<\/a><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Sant\u00e9, Droits Humains et Environnement en Bolivie Bienvenue \u00e0 l\u2019Institut pour le D\u00e9veloppement Humain, IDH Suisse\u00a0 IDH Suisse est une organisation \u00e0 but non lucratif, cr\u00e9\u00e9e en 2017. Notre principale mission est de soutenir les activit\u00e9s de l\u2019IpDH Bolivia, l\u2019Instituto para el Desarrollo Humano\u00a0dans son engagement envers la population locale [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/template-pagebuilder-full-width.php","meta":{"_eb_attr":"","footnotes":""},"class_list":["post-1249","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/pages\/1249","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/comments?post=1249"}],"version-history":[{"count":139,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/pages\/1249\/revisions"}],"predecessor-version":[{"id":1778,"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/pages\/1249\/revisions\/1778"}],"wp:attachment":[{"href":"https:\/\/preprod.idhsuisse.ch\/index.php\/wp-json\/wp\/v2\/media?parent=1249"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}